{"id":68397,"date":"2025-11-10T12:49:26","date_gmt":"2025-11-10T12:49:26","guid":{"rendered":"https:\/\/gripnijmegen.nl\/boulderhal\/?p=68397"},"modified":"2025-11-10T13:02:30","modified_gmt":"2025-11-10T13:02:30","slug":"grip-open-2025","status":"publish","type":"post","link":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/","title":{"rendered":"GRIP OPEN 2025"},"content":{"rendered":"\n<div class=\"wp-block-gutsliders-photo-carousel gutslider-447bd189 nav_outside nav_cc has__pagination\" data-swiper-options=\"{&quot;slidesPerView&quot;:1,&quot;spaceBetween&quot;:0,&quot;loop&quot;:true,&quot;autoplay&quot;:false,&quot;speed&quot;:800,&quot;effect&quot;:&quot;slide&quot;,&quot;keyboard&quot;:{&quot;enabled&quot;:false},&quot;mousewheel&quot;:false,&quot;breakpoints&quot;:{&quot;320&quot;:{&quot;slidesPerView&quot;:1,&quot;spaceBetween&quot;:0},&quot;768&quot;:{&quot;slidesPerView&quot;:2,&quot;spaceBetween&quot;:15},&quot;1025&quot;:{&quot;slidesPerView&quot;:2,&quot;spaceBetween&quot;:15}},&quot;navigation&quot;:{&quot;nextEl&quot;:&quot;.gutslider-447bd189 .swiper-button-next&quot;,&quot;prevEl&quot;:&quot;.gutslider-447bd189 .swiper-button-prev&quot;},&quot;pagination&quot;:{&quot;el&quot;:&quot;.gutslider-447bd189 .swiper-pagination&quot;,&quot;type&quot;:&quot;bullets&quot;,&quot;dynamicBullets&quot;:false,&quot;clickable&quot;:true}}\"><div class=\"swiper\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-39.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-75.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-53-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-87.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-108.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-111.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-134.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-260.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-150-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-276.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-209.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-282.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-133-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-272.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-139.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-226-1.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-288.jpg\" alt=\"\" \/><\/div><\/div><div class=\"swiper-slide\"><div class=\"swiper-container-outer none\"><img decoding=\"async\" src=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-290.jpg\" alt=\"\" \/><\/div><\/div><\/div><\/div><div class=\"swiper-pagination\"><\/div><div class=\"gutslider-nav nav_outside nav_cc\"><div class=\"swiper-button-prev\"><\/div><div class=\"swiper-button-next\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Wat een dag! Van een volle kwalificatieronde tot een onvergetelijke finale op de Wave \u2013 de sfeer in de hal was fantastisch. Elk jaar lijkt het niveau weer hoger te liggen, en ook deze editie was daarop geen uitzondering.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dankjewel aan alle getalenteerde en gedreven klimmers die hebben meegedaan en de dag zo bijzonder maakten. Ook aan iedereen die kwam kijken, aanmoedigen en supporten: jullie energie zorgde voor een geweldige sfeer. En natuurlijk gefeliciteerd aan alle finalisten voor de indrukwekkende show die ze neer hebben gezet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alle foto\u2019s van het evenement vind je op onze <a href=\"https:\/\/www.facebook.com\/GripBoulderhal\/\">Facebookpagina<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wat een dag! Van een volle kwalificatieronde tot een onvergetelijke finale op de Wave \u2013 de sfeer in de<\/p>\n","protected":false},"author":9,"featured_media":68357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-68397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nieuws"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GRIP OPEN 2025 - GRIP Boulderhal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GRIP OPEN 2025 - GRIP Boulderhal\" \/>\n<meta property=\"og:description\" content=\"Wat een dag! Van een volle kwalificatieronde tot een onvergetelijke finale op de Wave \u2013 de sfeer in de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"GRIP Boulderhal\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T12:49:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T13:02:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1282\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jakob\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"jakob\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/\"},\"author\":{\"name\":\"jakob\",\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/#\\\/schema\\\/person\\\/0561f378c9158883aca6819b39054897\"},\"headline\":\"GRIP OPEN 2025\",\"datePublished\":\"2025-11-10T12:49:26+00:00\",\"dateModified\":\"2025-11-10T13:02:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/\"},\"wordCount\":98,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/GRIP-Open-4.jpg\",\"articleSection\":[\"Nieuws\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/\",\"url\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/\",\"name\":\"GRIP OPEN 2025 - GRIP Boulderhal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/GRIP-Open-4.jpg\",\"datePublished\":\"2025-11-10T12:49:26+00:00\",\"dateModified\":\"2025-11-10T13:02:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/#\\\/schema\\\/person\\\/0561f378c9158883aca6819b39054897\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/GRIP-Open-4.jpg\",\"contentUrl\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/GRIP-Open-4.jpg\",\"width\":1282,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/2025\\\/11\\\/10\\\/grip-open-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GRIP OPEN 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/#website\",\"url\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/\",\"name\":\"GRIP Boulderhal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/#\\\/schema\\\/person\\\/0561f378c9158883aca6819b39054897\",\"name\":\"jakob\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555c227d6e1b4db137e675aac1dd3df07dc0b7aa0a256b345866276634e64abc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555c227d6e1b4db137e675aac1dd3df07dc0b7aa0a256b345866276634e64abc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/555c227d6e1b4db137e675aac1dd3df07dc0b7aa0a256b345866276634e64abc?s=96&d=mm&r=g\",\"caption\":\"jakob\"},\"url\":\"https:\\\/\\\/gripnijmegen.nl\\\/boulderhal\\\/author\\\/jakob\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GRIP OPEN 2025 - GRIP Boulderhal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/","og_locale":"nl_NL","og_type":"article","og_title":"GRIP OPEN 2025 - GRIP Boulderhal","og_description":"Wat een dag! Van een volle kwalificatieronde tot een onvergetelijke finale op de Wave \u2013 de sfeer in de","og_url":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/","og_site_name":"GRIP Boulderhal","article_published_time":"2025-11-10T12:49:26+00:00","article_modified_time":"2025-11-10T13:02:30+00:00","og_image":[{"width":1282,"height":1920,"url":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-4.jpg","type":"image\/jpeg"}],"author":"jakob","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"jakob","Geschatte leestijd":"5 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/#article","isPartOf":{"@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/"},"author":{"name":"jakob","@id":"https:\/\/gripnijmegen.nl\/boulderhal\/#\/schema\/person\/0561f378c9158883aca6819b39054897"},"headline":"GRIP OPEN 2025","datePublished":"2025-11-10T12:49:26+00:00","dateModified":"2025-11-10T13:02:30+00:00","mainEntityOfPage":{"@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/"},"wordCount":98,"commentCount":0,"image":{"@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-4.jpg","articleSection":["Nieuws"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/","url":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/","name":"GRIP OPEN 2025 - GRIP Boulderhal","isPartOf":{"@id":"https:\/\/gripnijmegen.nl\/boulderhal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/#primaryimage"},"image":{"@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-4.jpg","datePublished":"2025-11-10T12:49:26+00:00","dateModified":"2025-11-10T13:02:30+00:00","author":{"@id":"https:\/\/gripnijmegen.nl\/boulderhal\/#\/schema\/person\/0561f378c9158883aca6819b39054897"},"breadcrumb":{"@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/#primaryimage","url":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-4.jpg","contentUrl":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-content\/uploads\/sites\/3\/2025\/11\/GRIP-Open-4.jpg","width":1282,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/gripnijmegen.nl\/boulderhal\/2025\/11\/10\/grip-open-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gripnijmegen.nl\/boulderhal\/"},{"@type":"ListItem","position":2,"name":"GRIP OPEN 2025"}]},{"@type":"WebSite","@id":"https:\/\/gripnijmegen.nl\/boulderhal\/#website","url":"https:\/\/gripnijmegen.nl\/boulderhal\/","name":"GRIP Boulderhal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gripnijmegen.nl\/boulderhal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/gripnijmegen.nl\/boulderhal\/#\/schema\/person\/0561f378c9158883aca6819b39054897","name":"jakob","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/555c227d6e1b4db137e675aac1dd3df07dc0b7aa0a256b345866276634e64abc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/555c227d6e1b4db137e675aac1dd3df07dc0b7aa0a256b345866276634e64abc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/555c227d6e1b4db137e675aac1dd3df07dc0b7aa0a256b345866276634e64abc?s=96&d=mm&r=g","caption":"jakob"},"url":"https:\/\/gripnijmegen.nl\/boulderhal\/author\/jakob\/"}]}},"_links":{"self":[{"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/posts\/68397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/comments?post=68397"}],"version-history":[{"count":7,"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/posts\/68397\/revisions"}],"predecessor-version":[{"id":68410,"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/posts\/68397\/revisions\/68410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/media\/68357"}],"wp:attachment":[{"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/media?parent=68397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/categories?post=68397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gripnijmegen.nl\/boulderhal\/wp-json\/wp\/v2\/tags?post=68397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}